{"id":5679,"date":"2026-04-09T10:21:00","date_gmt":"2026-04-09T14:21:00","guid":{"rendered":"https:\/\/zocalo.cl\/enamoralaverdad\/?p=5679"},"modified":"2026-04-09T16:24:44","modified_gmt":"2026-04-09T20:24:44","slug":"taller-la-presencia-del-corazon","status":"publish","type":"post","link":"https:\/\/zocalo.cl\/enamoralaverdad\/taller-la-presencia-del-corazon\/","title":{"rendered":"Taller: La Presencia del Coraz\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En la profundidad de nuestro coraz\u00f3n, de nuestro cuarto chakra, yace la&nbsp; Chispa Divina, la Gota Primordial&nbsp; de nuestra existencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es una fuente infinita de calma, de sabidur\u00eda, amor, compasi\u00f3n y neutralidad, que ignoramos en esta sociedad occidental y que hoy te invita a volver a casa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Te convoco a un encuentro para hacer consciente esta Presencia. No es una t\u00e9cnica mental, es una invitaci\u00f3n a sentir, observar y reconocer c\u00f3mo cambia nuestra percepci\u00f3n de la vida cuando nos situamos en esa inmensidad amorosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este taller aprender\u00e1s a:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Llamar a tu esencia: Hacer pausas breves de conexi\u00f3n profunda en tu d\u00eda a d\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Decidir desde la neutralidad: Usar el coraz\u00f3n como br\u00fajula, soltando los juicios y el ruido de la mente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vivir el presente: Habitar el \u00abaqu\u00ed y ahora\u00bb desde la calma que solo el centro de nuestro pecho conoce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando aprendes a evocar y luego permanecer en esa esencia, todo se vuelve distinto. La crisis se transforma en observaci\u00f3n y la duda en claridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Todo ser\u00e1 distinto&#8230;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcc5 Fecha: Mi\u00e9rcoles 6 y Jueves 7 de Mayo<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u23f0 Hora: 20 a 22:30 hrs, hora de Chile<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udccd Lugar: Online (llamada grupal por Whatsapp)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udcb0 Inversi\u00f3n: 30.000 CLP o 45 USD<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\ud83d\udc49 Cupos limitados. Reserva tu lugar escribiendo al: +56987695497<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Testimonios:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8216;\u00bbUn taller lleno de sorpresas, al menos para mi. Poderosa herramienta de autoconocimiento. Qued\u00e9 muy contenta. Gran experiencia.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMi sensaci\u00f3n es que fue una linda experiencia para todas. Una gran herramienta.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMuy contenta y muy agradecida por este taller, este espacio de aprendizaje y compartir experiencias.&nbsp; Y ense\u00f1ar un tan potente recurso para llegar a un estado de claridad y calma&#8230; Gracias de coraz\u00f3n \u2764\ufe0f.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abMuy intuitivo y tambi\u00e9n muy \u00abr\u00e1pido\u00bb y muy potente experiencia para poder aplicarlo en la vida diaria.\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Namast\u00e9 \ud83d\ude4f&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">#taller #presenciadelcorazon #lachispadivina #PAS #meditaci\u00f3n<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2-819x1024.jpg\" alt=\"\" class=\"wp-image-5680\" style=\"width:450px\" srcset=\"https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2-819x1024.jpg 819w, https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2-600x750.jpg 600w, https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2-240x300.jpg 240w, https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2-768x960.jpg 768w, https:\/\/zocalo.cl\/enamoralaverdad\/wp-content\/uploads\/2026\/04\/taller-presencia-2.jpg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>En la profundidad de nuestro coraz\u00f3n, de nuestro cuarto chakra, yace la&nbsp; Chispa Divina, la Gota Primordial&nbsp; de nuestra existencia. Es una fuente infinita de calma, de sabidur\u00eda, amor, compasi\u00f3n y neutralidad, que ignoramos en esta sociedad occidental y que hoy te invita a volver a casa. . Te convoco a un encuentro para hacer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"_joinchat":[],"footnotes":""},"categories":[13,14,16],"tags":[117,150,171,199,200],"class_list":["post-5679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-talleres","category-terapias-energeticas","category-vivir-consciente","tag-meditacion","tag-presencia-del-corazon","tag-talleres","tag-vivir-consciente","tag-vivir-mejor"],"_links":{"self":[{"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/posts\/5679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/comments?post=5679"}],"version-history":[{"count":0,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/posts\/5679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/media\/5680"}],"wp:attachment":[{"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/media?parent=5679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/categories?post=5679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zocalo.cl\/enamoralaverdad\/wp-json\/wp\/v2\/tags?post=5679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}